{"id":849,"date":"2024-12-04T15:31:37","date_gmt":"2024-12-04T15:31:37","guid":{"rendered":"https:\/\/altitudefc.com\/?page_id=849"},"modified":"2024-12-04T15:31:37","modified_gmt":"2024-12-04T15:31:37","slug":"connaitre-les-procedures-collectives-redressement-et-liquidation-judiciaire","status":"publish","type":"page","link":"https:\/\/altitudefc.com\/index.php\/connaitre-les-procedures-collectives-redressement-et-liquidation-judiciaire\/","title":{"rendered":"Conna\u00eetre Les Proc\u00e9dures Collectives\u00a0: Redressement et Liquidation Judiciaire"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb type=\u00a0\u00bb4_4&Prime; theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<blockquote class=\"blockquote\">\n<p>Cette formation a \u00e9t\u00e9 con\u00e7ue pour vous permettre de ma\u00eetriser le cadre r\u00e8glementaire r\u00e9gissant la situation des entreprises en difficult\u00e9 et les proc\u00e9dures collectives et de mesurer tous les enjeux en termes de responsabilit\u00e9s.<\/p>\n<\/blockquote>\n<h2>Objectifs :<\/h2>\n<p>Pour recouvrer ses cr\u00e9ances aupr\u00e8s d\u2019une entreprise en difficult\u00e9, il faut imp\u00e9rativement ma\u00eetriser le d\u00e9roulement des proc\u00e9dures collectives afin d\u2019acqu\u00e9rir une m\u00e9thodologie de suivi des dossiers,\u00a0afin de contr\u00f4ler et d\u2019accomplir, dans les d\u00e9lais les \u00e9tapes li\u00e9s aux proc\u00e9dures de d\u00e9faillances des entreprises.<\/p>\n<h2>Pr\u00e9-requis :<\/h2>\n<p>Cette formation ne n\u00e9cessite pas de pr\u00e9requis<\/p>\n<h2>Cible :<\/h2>\n<p>Tous les collaborateurs des services contentieux, comptables et juridiques, ainsi que les gestionnaires de dossiers clients et les chefs d\u2019entreprise.<\/p>\n<h2>Dur\u00e9e :<\/h2>\n<p>2 jours soit 14 heures espac\u00e9es dans le temps.<\/p>\n<h2>Contenu :<\/h2>\n<p>&#8211; La pr\u00e9vention des difficult\u00e9s des entreprises,<br \/>&#8211; Les crit\u00e8res d\u2019ouverture de la proc\u00e9dure de redressement judiciaire,<br \/>&#8211; Les organes de la proc\u00e9dure,<br \/>&#8211; Les effets du jugement d\u2019ouverture,<br \/>&#8211; Le sort de la proc\u00e9dure,<br \/>&#8211; La d\u00e9fense des cr\u00e9anciers ordinaires,<br \/>&#8211; Les autres possibilit\u00e9s de recouvrement des cr\u00e9ances.<\/p>\n<h2>Modalit\u00e9s d\u2019acc\u00e8s :<\/h2>\n<p>Formation possible en individuel \/ \u00e0 la carte<\/p>\n<h2>Constitution des groupes :<\/h2>\n<p>&#8211; En INTRA : Groupe de 12 personnes maximum. Formation possible dans vos locaux (nous consulter)<br \/>D\u00e9lais d\u2019acc\u00e8s : en fonction des disponibilit\u00e9s des collaborateurs et du consultant-formateur<br \/>&#8211; En INTER : la formation sera mise en place sous r\u00e9serve d\u2019atteindre un quota de 8 participants minimum par groupe (formation dans les locaux d\u2019ALTITUDE)<br \/>D\u00e9lais d\u2019acc\u00e8s :\u00a0en fonction des disponibilit\u00e9s du consultant-formateur et sous r\u00e9serve d\u2019atteindre le quota de participants<br \/>&#8211; Formule personnalis\u00e9e &#8211;\u00a0D\u00e9lais d\u2019acc\u00e8s : en fonction des disponibilit\u00e9s du demandeur et de celles du consultant-formateur<\/p>\n<h1>Modalit\u00e9s, moyens et m\u00e9thodes mobilis\u00e9es et modalit\u00e9s d\u2019\u00e9valuation :<\/h1>\n<h2>Approche et m\u00e9thodes p\u00e9dagogiques :<\/h2>\n<h3><strong>En amont de la formation :<\/strong><\/h3>\n<p>Dans tous les cas, un audit t\u00e9l\u00e9phonique pr\u00e9alable nous permet de d\u00e9terminer et fixer la meilleure approche p\u00e9dagogique pour atteindre une qualit\u00e9 de formation optimale \u2013 Test de positionnement<\/p>\n<p>Le cours sera dispens\u00e9 dans un langage simple et clair avec l\u2019introduction de termes techniques \u00e0 conna\u00eetre et \u00e0 ma\u00eetriser.<br \/>La th\u00e9orie sera illustr\u00e9e par des mises en situations concr\u00e8tes.<\/p>\n<p>&#8211; Accueil des stagiaires dans une salle d\u00e9di\u00e9e \u00e0 la formation.<br \/>&#8211; Les apports th\u00e9oriques sont suivis de mises en pratique.<br \/>&#8211; Jeux ludiques \u00e0 vis\u00e9e p\u00e9dagogique<br \/>&#8211; Tests, Quiz en salle<br \/>&#8211; Autodiagnostics<br \/>&#8211; Evaluations<br \/>&#8211; Brainstorming<br \/>&#8211; Exercices de cr\u00e9ativit\u00e9<br \/>&#8211; Travail en sous groupe<br \/>&#8211; Transmission par courrier \u00e9lectronique de documents supports \u00e0 la suite de la formation.<\/p>\n<h2>Dispositif de suivi de l\u2019ex\u00e9cution et d\u2019\u00e9valuation des r\u00e9sultats de la formation :<\/h2>\n<p>&#8211; Feuilles de pr\u00e9sence,<br \/>&#8211; Formulaire d\u2019\u00e9valuation de la formation,<br \/>&#8211; QUIZ, jeux, jeux de r\u00f4le, QCM etc\u2026 en cours de formation<\/p>\n<h2>Profil du formateur (Exemple de) :<\/h2>\n<p><b>&#8211; Dipl\u00f4mes\u00a0:\u00a0<\/b>BTS Action Commerciale.<br \/><b>&#8211; Titres\u00a0:\u00a0<\/b>Responsable commerciale d\u2019un bureau de gestion et de recouvrement.<br \/><b>&#8211; R\u00e9f\u00e9rences\u00a0:\u00a0<\/b>21 ans d\u2019exp\u00e9rience dans la gestion du cr\u00e9dit client.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb3_4,1_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb11px|17px|11px|17px|true|true\u00a0\u00bb border_width_all=\u00a0\u00bb1px\u00a0\u00bb border_color_all=\u00a0\u00bbrgba(0,0,0,0.12)\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_column type=\u00a0\u00bb3_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<h2>Notre \u00e9quipe est \u00e0 votre disposition pour r\u00e9pondre \u00e0 toute autre question au sujet de ces formations.<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][et_pb_button button_url=\u00a0\u00bbhttps:\/\/altitudefc.com\/index.php\/contact\u00a0\u00bb button_text=\u00a0\u00bbCONTACTEZ-NOUS\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb17px\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bb#b51dd3&Prime; button_border_radius=\u00a0\u00bb13px\u00a0\u00bb custom_margin=\u00a0\u00bb14px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cette formation a \u00e9t\u00e9 con\u00e7ue pour vous permettre de ma\u00eetriser le cadre r\u00e8glementaire r\u00e9gissant la situation des entreprises en difficult\u00e9 et les proc\u00e9dures collectives et de mesurer tous les enjeux en termes de responsabilit\u00e9s. Objectifs : Pour recouvrer ses cr\u00e9ances aupr\u00e8s d\u2019une entreprise en difficult\u00e9, il faut imp\u00e9rativement ma\u00eetriser le d\u00e9roulement des proc\u00e9dures collectives afin [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-849","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/altitudefc.com\/index.php\/wp-json\/wp\/v2\/pages\/849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/altitudefc.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/altitudefc.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/altitudefc.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/altitudefc.com\/index.php\/wp-json\/wp\/v2\/comments?post=849"}],"version-history":[{"count":2,"href":"https:\/\/altitudefc.com\/index.php\/wp-json\/wp\/v2\/pages\/849\/revisions"}],"predecessor-version":[{"id":851,"href":"https:\/\/altitudefc.com\/index.php\/wp-json\/wp\/v2\/pages\/849\/revisions\/851"}],"wp:attachment":[{"href":"https:\/\/altitudefc.com\/index.php\/wp-json\/wp\/v2\/media?parent=849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}